{"id":2107,"date":"2015-04-27T12:51:37","date_gmt":"2015-04-27T12:51:37","guid":{"rendered":"http:\/\/www.neb-online.de\/?page_id=2107"},"modified":"2016-02-18T16:55:07","modified_gmt":"2016-02-18T15:55:07","slug":"routine-pcr-en","status":"publish","type":"page","link":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/","title":{"rendered":"Standard PCR (en)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":2092,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2107","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Standard PCR (en) - New England Biolabs GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Standard PCR (en) - New England Biolabs GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/\" \/>\n<meta property=\"og:site_name\" content=\"New England Biolabs GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-18T15:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neb-online.de\/wp-content\/uploads\/2019\/03\/NEB_GmbH_with-inspired-claim-square_4c.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/routine-pcr-en\\\/\",\"url\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/routine-pcr-en\\\/\",\"name\":\"Standard PCR (en) - New England Biolabs GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neb-online.de\\\/#website\"},\"datePublished\":\"2015-04-27T12:51:37+00:00\",\"dateModified\":\"2016-02-18T15:55:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/routine-pcr-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/routine-pcr-en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/routine-pcr-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PCR and DNA Amplification\",\"item\":\"https:\\\/\\\/www.neb-online.de\\\/en\\\/pcr-and-dna-amplification\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Routine PCR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neb-online.de\\\/#website\",\"url\":\"https:\\\/\\\/www.neb-online.de\\\/\",\"name\":\"New England Biolabs GmbH\",\"description\":\"Enabling Technologies in the Life Sciences\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neb-online.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Standard PCR (en) - New England Biolabs GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/","og_locale":"en_US","og_type":"article","og_title":"Standard PCR (en) - New England Biolabs GmbH","og_url":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/","og_site_name":"New England Biolabs GmbH","article_modified_time":"2016-02-18T15:55:07+00:00","og_image":[{"width":500,"height":266,"url":"https:\/\/www.neb-online.de\/wp-content\/uploads\/2019\/03\/NEB_GmbH_with-inspired-claim-square_4c.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/","url":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/","name":"Standard PCR (en) - New England Biolabs GmbH","isPartOf":{"@id":"https:\/\/www.neb-online.de\/#website"},"datePublished":"2015-04-27T12:51:37+00:00","dateModified":"2016-02-18T15:55:07+00:00","breadcrumb":{"@id":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/routine-pcr-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.neb-online.de\/en\/"},{"@type":"ListItem","position":2,"name":"PCR and DNA Amplification","item":"https:\/\/www.neb-online.de\/en\/pcr-and-dna-amplification\/"},{"@type":"ListItem","position":3,"name":"Routine PCR"}]},{"@type":"WebSite","@id":"https:\/\/www.neb-online.de\/#website","url":"https:\/\/www.neb-online.de\/","name":"New England Biolabs GmbH","description":"Enabling Technologies in the Life Sciences","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neb-online.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/pages\/2107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/comments?post=2107"}],"version-history":[{"count":2,"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/pages\/2107\/revisions"}],"predecessor-version":[{"id":8385,"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/pages\/2107\/revisions\/8385"}],"up":[{"embeddable":true,"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/pages\/2092"}],"wp:attachment":[{"href":"https:\/\/www.neb-online.de\/en\/wp-json\/wp\/v2\/media?parent=2107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}